{"id":10028,"date":"2021-08-09T16:22:49","date_gmt":"2021-08-09T21:22:49","guid":{"rendered":"https:\/\/thelidjifirm.com\/?page_id=10028"},"modified":"2024-05-31T16:05:19","modified_gmt":"2024-05-31T21:05:19","slug":"demanda-contra-phillips-cpap","status":"publish","type":"page","link":"https:\/\/thelidjifirm.com\/es\/demanda-contra-phillips-cpap\/","title":{"rendered":"Demanda contra Phillips CPAP"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10028\" class=\"elementor elementor-10028 elementor-10027\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37d7ba45 elementor-section-stretched elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"37d7ba45\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28a5680f\" data-id=\"28a5680f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69f1317 elementor-widget elementor-widget-image\" data-id=\"69f1317\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1440\" height=\"700\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/philips-cpap-recall-lawsuit-the-lidji-firm.jpg\" class=\"attachment-full size-full wp-image-10036\" alt=\"Philips CPAP Recall | demanda La firma Lidji | Abogado de Lesiones Personales\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/philips-cpap-recall-lawsuit-the-lidji-firm.jpg 1440w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/philips-cpap-recall-lawsuit-the-lidji-firm-150x73.jpg 150w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45b62a9 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"45b62a9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7aeba92\" data-id=\"7aeba92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b561aa elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"6b561aa\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h1 class=\"raven-heading raven-heading-h1\"><span class=\"raven-heading-title \"><div class=\"tx\">En todo el pa\u00eds<\/div> \nDemandas contra Phillips CPAP<\/span><\/h1><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1390900 elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"1390900\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h4 class=\"raven-heading raven-heading-h4\"><span class=\"raven-heading-title \">Abogados de lesiones personales<\/span><\/h4><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90aefbd elementor-mobile-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-raven-button\" data-id=\"90aefbd\" data-element_type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"#free-case-evaluation\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tREVISI\u00d3N GRATUITA DEL CASO\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d446c8a\" data-id=\"d446c8a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-317888b4 elementor-section-stretched elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"317888b4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7092c58e\" data-id=\"7092c58e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caa0032 prac-body elementor-widget elementor-widget-text-editor\" data-id=\"caa0032\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando tienes una enfermedad que afecta gravemente a tu vida y a tu salud, probablemente est\u00e9s centrado en lo que puedes hacer para mejorar. Muchas personas que padecen apnea del sue\u00f1o utilizaron un aparato de Philips Respironics, y en lugar de mejorarles, probablemente les empeor\u00f3 e incluso provoc\u00f3 c\u00e1ncer a muchos usuarios. Estos resultados condujeron a la demanda de retirada del CPAP de Philips.<\/p>\n<p>No hay nada m\u00e1s frustrante que depositar tu confianza en un aparato m\u00e9dico y en una empresa que afirma que puede ayudarte, s\u00f3lo para que empeores con su tratamiento, y los abogados de The Lidji Firm especializados en demandas por la retirada de Philips del CPAP est\u00e1n preparados para ayudarte.<\/p>\n<p>Si has experimentado efectos secundarios negativos como consecuencia de la m\u00e1quina para la apnea del sue\u00f1o Phillips, queremos ayudarte. El Bufete Lidji cuenta con cientos de abogados en todo Estados Unidos. Nuestra mayor preocupaci\u00f3n es asegurarnos de que obtienes la justicia y la indemnizaci\u00f3n que mereces. A lo largo de los a\u00f1os, nuestro exitoso bufete ha recuperado m\u00e1s de diez mil millones de d\u00f3lares para nuestros clientes. No dudes en ponerte en contacto con nosotros.  <a href=\"https:\/\/thelidjifirm.com\/es\/evaluacion-de-caso-gratuita\/\"><strong>Ponte en contacto con The Lidji Firm hoy mismo para obtener una evaluaci\u00f3n gratuita de tu caso de retirada del CPAP de Philips.<\/strong><\/a><\/p>\n<h2>El problema de las m\u00e1quinas Phillips para CPAP y apnea del sue\u00f1o<\/h2>\n<p>Philips retir\u00f3 millones de CPAP y otras m\u00e1quinas para la apnea del sue\u00f1o porque muchos usuarios respiraban espuma t\u00f3xica causada por un grave problema con sus m\u00e1quinas. Respirar esta espuma t\u00f3xica puede provocar c\u00e1ncer y otros problemas de salud importantes. La espuma iba directamente al tubo que los usuarios utilizaban para respirar correctamente mientras dorm\u00edan.  <\/p>\n<p>Aparte de provocar c\u00e1ncer, lo cual es obviamente grave y completamente inaceptable, muchos usuarios tambi\u00e9n declararon dolores de cabeza, irritaciones de las v\u00edas respiratorias superiores, tos, presi\u00f3n en el pecho, infecciones sinusales, asma, da\u00f1os en el h\u00edgado y los ri\u00f1ones, n\u00e1useas, v\u00f3mitos y aumento de los problemas respiratorios.<\/p>\n<h2>Demanda colectiva por retirada del mercado de CPAP de Philips<\/h2>\n<p>En junio de 2021, se present\u00f3 una demanda colectiva contra Philips en Massachusetts. La demanda afirma que Phillips conoc\u00eda la espuma t\u00f3xica y los graves problemas de salud que estaba causando a la gente desde hac\u00eda a\u00f1os. Se afirma que los usuarios llevaban muchos a\u00f1os quej\u00e1ndose de los problemas, pero Philips no emiti\u00f3 una advertencia p\u00fablica hasta abril de 2021. Pasaron otros dos meses, hasta el 14 de junio de 2021, antes de que Philips retirara oficialmente los aparatos.<\/p>\n<p>Curiosamente, Philips no anunci\u00f3 la retirada de sus m\u00e1quinas hasta m\u00e1s o menos el momento en que iban a sacar un aparato m\u00e1s nuevo. Muchos pacientes que necesitan desesperadamente estos dispositivos no tuvieron m\u00e1s remedio que comprar la m\u00e1quina m\u00e1s nueva, lo que significa que Philips sigui\u00f3 obteniendo beneficios incluso despu\u00e9s de hacer p\u00fablica la retirada de su m\u00e1quina actual.<\/p>\n<h2>La demanda de retirada del CPAP de Philips se basa en 2 infracciones<\/h2>\n<ul>\n<li>\n<h3>Defecto de dise\u00f1o<\/h3>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Una de las razones por las que la gente presentaba demandas contra Philips es por el simple hecho de que los aparatos que vend\u00edan a los pacientes eran defectuosos y peligrosos. La espuma que utilizaron en el aparato es tan peligrosa que cuando se degrada provoca c\u00e1ncer. Esto por s\u00ed solo podr\u00eda ser problema suficiente para una demanda.<\/p>\n<ul>\n<li>\n<h3>Falta de advertencia<\/h3>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Philips no s\u00f3lo utiliz\u00f3 en sus dispositivos m\u00e9dicos material incre\u00edblemente peligroso, sino que no advirti\u00f3 al p\u00fablico en cuanto tuvo conocimiento de los riesgos. Se alega que los usuarios llevaban <em>a\u00f1os<\/em> quej\u00e1ndose de problemas de salud como consecuencia de la espuma. Como m\u00ednimo, Philips se dio cuenta del problema en abril de 2021 y no retir\u00f3 el producto hasta mediados de junio de 2021. Esto significa que la gente sigui\u00f3 comprando y utilizando las m\u00e1quinas durante al menos dos meses, a pesar de que Philips conoc\u00eda perfectamente los riesgos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1948ca79 prac-form\" data-id=\"1948ca79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cd6add elementor-align-center elementor-widget elementor-widget-raven-heading\" data-id=\"3cd6add\" data-element_type=\"widget\" id=\"free-case-evaluation\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">EVALUACI\u00d3N DE CASO GRATUITA<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f63dc elementor-widget elementor-widget-shortcode\" data-id=\"f6f63dc\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-6872\"><form id=\"wpforms-form-6872\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6872\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/10028\" data-token=\"b655033b7674ce457e7d66820c562586\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-6872-field_0-container\" class=\"wpforms-field wpforms-field-name wpf_fce fce_name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6872-field_0\">Nombre completo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-6872-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nombre completo\" required><\/div><div id=\"wpforms-6872-field_5-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half wpforms-first wpf_fce fce_phone\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6872-field_5\">Tel\u00e9fono <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-6872-field_5\" class=\"wpforms-field-large wpforms-field-required wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][5]\" placeholder=\"Tel\u00e9fono\" required><\/div><div id=\"wpforms-6872-field_1-container\" class=\"wpforms-field wpforms-field-email wpf_fce fce_email wpforms-one-half\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6872-field_1\">Correo Electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6872-field_1\" class=\"wpforms-field-large wpforms-field-required\" data-rule-restricted-email=\"1\" name=\"wpforms[fields][1]\" placeholder=\"Correo Electr\u00f3nico\" spellcheck=\"false\" required><\/div><div id=\"wpforms-6872-field_4-container\" class=\"wpforms-field wpforms-field-select wpf_fce fce_casetype wpforms-field-select-style-modern\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6872-field_4\">Tipo de caso<\/label><select id=\"wpforms-6872-field_4\" class=\"wpforms-field-medium choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"1\" name=\"wpforms[fields][4][]\" multiple=\"multiple\"><option value=\"\" class=\"placeholder\" disabled >Tipo de caso (opcional)<\/option><option value=\"Agravio masivo - BadPill\" >Agravio masivo - BadPill<\/option><option value=\"Demanda de Camp Lejeune\" >Demanda de Camp Lejeune<\/option><option value=\"Defecto de nacimiento infantil \u2013 Lesi\u00f3n de nacimiento\" >Defecto de nacimiento infantil \u2013 Lesi\u00f3n de nacimiento<\/option><option value=\"Demanda de Johnson &amp; Johnson Powder\" >Demanda de Johnson &amp; Johnson Powder<\/option><option value=\"Demanda de CPAP de Phillips\" >Demanda de CPAP de Phillips<\/option><option value=\"Demanda de Paraquat \" >Demanda de Paraquat <\/option><option value=\"Demanda de Roundup\" >Demanda de Roundup<\/option><option value=\"C\u00e1ncer de Zantac\" >C\u00e1ncer de Zantac<\/option><option value=\"Demandas de Januvia\" >Demandas de Januvia<\/option><option value=\"Demanda por problemas card\u00edacos de Zofran\" >Demanda por problemas card\u00edacos de Zofran<\/option><option value=\"Mala praxis m\u00e9dica\" >Mala praxis m\u00e9dica<\/option><option value=\"Demanda de filtro IVC\" >Demanda de filtro IVC<\/option><option value=\"Lesiones personales\" >Lesiones personales<\/option><option value=\"Accidente de cami\u00f3n\" >Accidente de cami\u00f3n<\/option><option value=\"Accidente de auto\" >Accidente de auto<\/option><option value=\"Accidente de motocicleta\" >Accidente de motocicleta<\/option><option value=\"Accidentes por conducir ebrio\" >Accidentes por conducir ebrio<\/option><option value=\"Responsabilidad de la tienda de dram\" >Responsabilidad de la tienda de dram<\/option><option value=\"Accidentes de construcci\u00f3n\" >Accidentes de construcci\u00f3n<\/option><option value=\"Responsabilidad de los locales\" >Responsabilidad de los locales<\/option><option value=\"Responsabilidad del producto\" >Responsabilidad del producto<\/option><option value=\"Muerte injusta\" >Muerte injusta<\/option><\/select><\/div><div id=\"wpforms-6872-field_2-container\" class=\"wpforms-field wpforms-field-textarea wpf_fce fce_casedetail\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-6872-field_2\">Detalle del caso <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-6872-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Por favor describe tu caso\" required><\/textarea><\/div><div id=\"wpforms-6872-field_9-container\" class=\"wpforms-field wpforms-field-date-time wpf_fce wpforms-one-half wpforms-first\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-6872-field_9\">Fecha del accidente <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-6872-field_9\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"F j, Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][9][date]\" placeholder=\"Por favor seleccione\" required><a title=\"Borrar fecha\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-6872-field_7-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpf_fce wpforms-list-2-columns\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-6872-field_7\">\u00bfYa tienes abogado? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-6872-field_7\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-6872-field_7_1\" name=\"wpforms[fields][7]\" value=\"S\u00ed\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6872-field_7_1\">S\u00ed<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-6872-field_7_2\" name=\"wpforms[fields][7]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-6872-field_7_2\">No<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6872\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"8\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6872\" class=\"wpforms-submit\" data-alt-text=\"Enviar...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/thelidjifirm.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\" title=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efed255 animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"efed255\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" width=\"569\" height=\"500\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/mary-jo-betzen-lawyer-the-lidji-firm-pernoal-injury-attorney-texas.png\" class=\"attachment-full size-full wp-image-4834\" alt=\"Mary Jo Betzen | Abogada | La Firma Lidji | Abogados de lesiones personales | Dallas Houston Texas\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/mary-jo-betzen-lawyer-the-lidji-firm-pernoal-injury-attorney-texas.png 569w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/mary-jo-betzen-lawyer-the-lidji-firm-pernoal-injury-attorney-texas-150x132.png 150w\" sizes=\"(max-width: 569px) 100vw, 569px\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42bf64a6 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-raven-heading\" data-id=\"42bf64a6\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">ESTAMOS AQU\u00cd<br> <div style=\"font-size: 18px; line-height: 1.3em; font-weight: 400; margin-top: 5px;\">para ayudarte a conseguir la<br>  dinero que te mereces.<\/div><\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d9e102 elementor-mobile-align-center elementor-widget-mobile__width-initial elementor-align-center elementor-widget elementor-widget-raven-button\" data-id=\"33d9e102\" data-element_type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"tel:(800)%20223-7455\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tLL\u00c1MANOS\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b81ddd7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b81ddd7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-de83247\" data-id=\"de83247\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1799fee elementor-widget elementor-widget-raven-image\" data-id=\"1799fee\" data-element_type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset&quot;:120,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/januvia-lawsuits-the-lidji-firm-personal-injury-lawyer-2.jpg\" class=\"attachment-full size-full wp-image-8193\" alt=\"Demandas de Januvia | La firma LIDJI | Abogado de lesiones personales | Dallas Houston Texas\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/januvia-lawsuits-the-lidji-firm-personal-injury-lawyer-2.jpg 500w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/januvia-lawsuits-the-lidji-firm-personal-injury-lawyer-2-150x150.jpg 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8356749\" data-id=\"8356749\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa73cd prac-body prac-b2 elementor-widget elementor-widget-text-editor\" data-id=\"ffa73cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\n<h2><span style=\"text-decoration: underline;\">Preguntas frecuentes<\/span><\/h2>\n<h3><strong>\u00bfQu\u00e9 es la apnea del sue\u00f1o?<\/strong><\/h3>\n<p>La apnea del sue\u00f1o es un trastorno grave del sue\u00f1o en el que la respiraci\u00f3n de una persona se detiene y se inicia repetidamente durante el tiempo que duerme. Hay tres tipos principales de apnea del sue\u00f1o:<\/p>\n<ol>\n<li>Apnea <strong>obstructiva<\/strong> del sue\u00f1o. Es la forma m\u00e1s frecuente de apnea del sue\u00f1o y se produce cuando se relajan los m\u00fasculos de la garganta. Cuando esto ocurre, no puedes obtener suficiente aire, lo que reduce el nivel de ox\u00edgeno en la sangre.<\/li>\n<li><strong>Apnea central del sue\u00f1o.<\/strong>  Este tipo de apnea del sue\u00f1o se produce cuando el cerebro no env\u00eda las se\u00f1ales adecuadas a los m\u00fasculos que controlan la respiraci\u00f3n. Puedes despertarte con dificultad respiratoria o tener dificultades para conciliar el sue\u00f1o o permanecer dormido.<\/li>\n<li><strong>S\u00edndrome de Apnea Compleja del Sue\u00f1o. Este<\/strong>  tambi\u00e9n se denomina apnea central del sue\u00f1o emergente del tratamiento. Se produce cuando tienes tanto apnea obstructiva del sue\u00f1o como apnea central del sue\u00f1o.<\/li>\n<\/ol>\n<h3><strong>\u00bfQu\u00e9 es una m\u00e1quina CPAP?<\/strong><\/h3>\n<p>Una m\u00e1quina de presi\u00f3n positiva continua en las v\u00edas respiratorias (CPAP) es el m\u00e9todo m\u00e1s com\u00fanmente prescrito para tratar la apnea del sue\u00f1o. Este dispositivo m\u00e9dico env\u00eda un flujo constante de ox\u00edgeno a la boca y la nariz mientras duermes, lo que mantiene abiertas las v\u00edas respiratorias y te permite respirar con m\u00e1s normalidad.<\/p>\n<p>Las m\u00e1quinas CPAP tienen motores que generan un flujo constante de aire a presi\u00f3n que pasa por un filtro de aire y llega a un tubo flexible. El tubo suministra aire purificado a una mascarilla que sellas alrededor de la nariz o la boca mientras duermes.<\/p>\n<h3><strong>Qu\u00e9 m\u00e1quinas se retiraron<\/strong><\/h3>\n<p>Philips acab\u00f3 retirando millones de respiradores por el problema de la espuma. Adem\u00e1s de retirarse los aparatos para la apnea del sue\u00f1o, tambi\u00e9n se retiraron otros respiradores mec\u00e1nicos que salvan vidas. Las m\u00e1quinas retiradas son las siguientes<\/p>\n<ol>\n<li><a href=\"https:\/\/www.usa.philips.com\/healthcare\/product\/HCNOCTN447\/dreamstation-cpap-bi-level-therapy-systems\" target=\"_blank\" rel=\"noopener\">M\u00e1quinas DreamStation<\/a><\/li>\n<li>M\u00e1quinas de presi\u00f3n positiva continua en las v\u00edas respiratorias (CPAP)<\/li>\n<li>Presi\u00f3n positiva binivel en las v\u00edas respiratorias (PAP binivel)<\/li>\n<li>Ventiladores mec\u00e1nicos<\/li>\n<\/ol>\n<h3><strong>\u00bfQu\u00e9 es la espuma t\u00f3xica?<\/strong><\/h3>\n<p>La espuma t\u00f3xica que estaba causando graves problemas de salud a la gente es poliuretano con base de poli\u00e9ster. Mientras la gente utilizaba la m\u00e1quina, la espuma empez\u00f3 a degradarse en part\u00edculas muy peque\u00f1as que los usuarios respiraban o inger\u00edan. La espuma tambi\u00e9n produc\u00eda gases t\u00f3xicos, que causaban c\u00e1ncer, irritaci\u00f3n pulmonar y da\u00f1os org\u00e1nicos.<\/p>\n<h3><strong>\u00bfCu\u00e1nto tiempo llevan las m\u00e1quinas en el mercado?<\/strong><\/h3>\n<p>Estas m\u00e1quinas da\u00f1inas se venden a los pacientes desde 2009, lo que significa que algunos usuarios han estado expuestos a la espuma y los gases durante m\u00e1s de diez a\u00f1os.<\/p>\n<h3><strong>\u00bfPuedo presentar una demanda contra Phillips?<\/strong><\/h3>\n<p>Si utilizaste alguna de las m\u00e1quinas para la apnea del sue\u00f1o de Philips que han retirado del mercado recientemente, puedes tener derecho a presentar una demanda. Es importante que lleves un registro de cu\u00e1ndo utilizaste la m\u00e1quina y durante cu\u00e1nto tiempo. Toma nota tambi\u00e9n del dispositivo que utilizaste. Adem\u00e1s, \u00bfte han diagnosticado c\u00e1ncer o cualquier otro tipo de enfermedad que t\u00fa y tu m\u00e9dico cre\u00e1is que est\u00e1 relacionada con el aparato?  <\/p>\n<p>Si la respuesta es afirmativa, puede que tengas una reclamaci\u00f3n legal v\u00e1lida contra Phillips en la demanda de retirada del CPAP de Philips. Lo mejor que puedes hacer es ponerte en contacto inmediatamente con el bufete Lidji para una consulta gratuita. Podemos ayudarte a determinar si tienes una reclamaci\u00f3n viable o no. Tambi\u00e9n podemos ayudarte a obtener tu historial m\u00e9dico y a averiguar qu\u00e9 debes hacer a continuaci\u00f3n<\/p>\n<h2>\u00bfTengo derecho a una indemnizaci\u00f3n?<\/h2>\n<p>Sin duda es una posibilidad para la demanda de retirada del CPAP de Philips. Si determinamos que tienes una demanda viable, significa que creemos que tienes derecho a una indemnizaci\u00f3n. Si presentas una demanda y tenemos \u00e9xito en la negociaci\u00f3n de tu caso o ganamos en el juicio, podr\u00edas tener derecho a los siguientes tipos de indemnizaci\u00f3n:<\/p>\n<ul>\n<li><strong>Facturas m\u00e9dicas.<\/strong>  Si ganamos tu caso, deber\u00edas tener derecho al pago de las facturas m\u00e9dicas anteriores. Adem\u00e1s, es probable que puedas cobrar una indemnizaci\u00f3n por da\u00f1os y perjuicios que te ayude a pagar cualquier tratamiento o procedimiento m\u00e9dico que puedas necesitar en el futuro y que est\u00e9 relacionado con el uso de una m\u00e1quina Philips defectuosa para la apnea del sue\u00f1o.<\/li>\n<li><strong>P\u00e9rdida de ingresos.<\/strong>  Si has perdido ingresos por haber estado en el hospital a causa de una m\u00e1quina defectuosa para la apnea del sue\u00f1o, podr\u00e1s recuperar los ingresos perdidos. Esto incluye los ingresos que podr\u00edas perder en el futuro si ya no puedes trabajar.<\/li>\n<li><strong>Dolor y sufrimiento.<\/strong>  Cuando utilizas un producto sanitario, das por sentado que es seguro y que los fabricantes no te enga\u00f1an a sabiendas sobre su seguridad. Cuando descubres que has sufrido lesiones graves como consecuencia de su negligencia, suele ser emocionalmente doloroso y traumatizante. Podr\u00edas tener derecho a una indemnizaci\u00f3n por da\u00f1os y perjuicios por esta demanda de retirada del CPAP de Philips.<\/li>\n<li><strong>Da\u00f1os punitivos.<\/strong>  Los da\u00f1os punitivos se conceden como forma de castigar a las empresas y disuadirlas de incurrir en este tipo de comportamiento en el futuro. Philips sab\u00eda que sus aparatos eran defectuosos, pero sigui\u00f3 vendi\u00e9ndolos y no advirti\u00f3 al p\u00fablico. Esto es inconcebible. En un caso atroz como \u00e9ste, es probable que un tribunal conceda da\u00f1os punitivos si tienes \u00e9xito en tu caso.<\/li>\n<\/ul>\n<h2>El bufete Lidji puede ayudarte<\/h2>\n<p>En The Lidji Firm, nuestro trabajo consiste en ayudarte lo mejor posible. Tenemos abogados en todo el pa\u00eds, as\u00ed que, independientemente de d\u00f3nde hayas utilizado este dispositivo, podemos representarte. Si has sufrido alguna consecuencia para tu salud como consecuencia del uso de estos productos sanitarios Phillips, debes ponerte en contacto con nosotros inmediatamente. Podemos determinar si tienes derecho a presentar una demanda o no. Hablar con nosotros no te costar\u00e1 nada.  <\/p>\n<p>Adem\u00e1s, nunca nos pagar\u00e1s nada hasta que lleguemos a un acuerdo o ganemos tu caso en los tribunales. Los abogados del Bufete Lidji tienen experiencia, dedicaci\u00f3n y se preocupan de verdad por ti. Tratamos a todos nuestros clientes exactamente como querr\u00edamos que trataran a los miembros de nuestra propia familia. Ponte en contacto con nosotros ahora mismo y concierta una <a href=\"https:\/\/thelidjifirm.com\/es\/evaluacion-de-caso-gratuita\/\">evaluaci\u00f3n gratuita de tu caso<\/a> para que podamos ayudarte.  <\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6997d06a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6997d06a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bb3fed5\" data-id=\"5bb3fed5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-315dc02b elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-raven-heading\" data-id=\"315dc02b\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">Hable con Philips CPAP Recall Attorneys hoy<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-604d3838 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-raven-heading\" data-id=\"604d3838\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><div class=\"raven-heading raven-heading-div\"><span class=\"raven-heading-title \">Trabajar con un abogado experimentado es importante para ayudarlo a ganar el caso<\/span><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-547d518d elementor-reverse-mobile elementor-section-stretched elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"547d518d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44807cd6\" data-id=\"44807cd6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b510fd6 elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"3b510fd6\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \"><font size=\"5\"><i><b>Razones para elegir<\/b><\/i> <br><\/font>El bufete Lidji<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6b62e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d6b62e7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2410330 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2410330\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-602ca552\" data-id=\"602ca552\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ce478 animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"f7ce478\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/justice-scale-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4785\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2be016fb elementor-widget elementor-widget-icon-box\" data-id=\"2be016fb\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSin tarifas por adelantado\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSin recuperaci\u00f3n = sin tarifas. Si no ganamos su caso, no nos pagar\u00e1 ni un centavo Si no ganamos su caso, no nos pagar\u00e1 ni un centavo\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e6367f1\" data-id=\"6e6367f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ede078f animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"6ede078f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/lawyer-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4781\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d77b701 elementor-widget elementor-widget-icon-box\" data-id=\"d77b701\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAyuda 24\/7 para usted\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRespondemos llamadas y correos electr\u00f3nicos fuera de horario y fines de semana.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6eedd8f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6eedd8f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-783b014c\" data-id=\"783b014c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ccaabdf animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"1ccaabdf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/justice-court-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4783\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27b0c47a elementor-widget elementor-widget-icon-box\" data-id=\"27b0c47a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCredibilidad y experiencia\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHemos cerrado miles de casos para nuestros clientes a lo largo de 37 a\u00f1os\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a3c5c6d\" data-id=\"a3c5c6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41612054 animated-fast elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"41612054\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/brief-case-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4784\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fcdb9b5 elementor-widget elementor-widget-icon-box\" data-id=\"1fcdb9b5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCarga de casos limitados\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLimitamos nuestros casos para dedicar nuestro tiempo y energ\u00eda a los clientes que representamos\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49b48dce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49b48dce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66db8435\" data-id=\"66db8435\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58b8cc34 animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"58b8cc34\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:450}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/success-paper-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4782\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-300afe6e elementor-widget elementor-widget-icon-box\" data-id=\"300afe6e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHistorial de \u00e9xitos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros clientes han recibido importantes indemnizaciones gracias a nuestros litigios\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4409d8d7\" data-id=\"4409d8d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16562b1 animated-slow elementor-invisible elementor-widget elementor-widget-raven-image\" data-id=\"16562b1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:750}\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"70\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/gavel-icon-the-lidji-law-firm-dallas-personal-injury-attorney.svg\" class=\"attachment-full size-full wp-image-4786\" alt=\"Mejor abogado | BadPill | The Lidji Firm | Abogados de lesiones personales | Dallas Houston Texas\" title=\"\">\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-560812d6 elementor-widget elementor-widget-icon-box\" data-id=\"560812d6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tReputaci\u00f3n de \u00e9xito\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNuestros abogados han resuelto con \u00e9xito cientos de casos de lesiones personales y m\u00e1s de 100 casos de defectos de productos hasta su conclusi\u00f3n.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-183e65bb\" data-id=\"183e65bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ebca58 elementor-widget elementor-widget-image\" data-id=\"10ebca58\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"886\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/lidji-3-the-lidji-firm-personal-injury-attorney-texas.png\" class=\"attachment-full size-full wp-image-4830\" alt=\"I. Scott Lidji | Abogado | La Firma Lidji | Abogados de lesiones personales | Dallas Houston Texas\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/lidji-3-the-lidji-firm-personal-injury-attorney-texas.png 650w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/lidji-3-the-lidji-firm-personal-injury-attorney-texas-110x150.png 110w\" sizes=\"(max-width: 650px) 100vw, 650px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd7180f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dd7180f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7bcf4c8c\" data-id=\"7bcf4c8c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5032898a elementor-mobile-align-center elementor-widget__width-auto elementor-align-center elementor-widget elementor-widget-raven-button\" data-id=\"5032898a\" data-element_type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"#free-case-evaluation-2\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"raven-button-icon raven-button-icon-position-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tREVISI\u00d3N GRATUITA DEL CASO\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42ccd82e elementor-mobile-align-center elementor-widget-mobile__width-initial elementor-align-center elementor-widget__width-auto elementor-widget elementor-widget-raven-button\" data-id=\"42ccd82e\" data-element_type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"tel:(800)%20223-7455\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t<span class=\"raven-button-icon raven-button-icon-position-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tLLAME AHORA 24\/7\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<!-- dce invisible element 3256812e -->\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31c6a9b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"31c6a9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-932cffd\" data-id=\"932cffd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad6d681 elementor-widget elementor-widget-template\" data-id=\"ad6d681\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"11866\" class=\"elementor elementor-11866 elementor-11426\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5d04e3 elementor-section-full_width neww elementor-section-height-default elementor-section-height-default\" data-id=\"e5d04e3\" data-element_type=\"section\" id=\"free-case-review\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-460a169\" data-id=\"460a169\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5dafe8 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"e5dafe8\" data-element_type=\"widget\" id=\"ctbg\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"436\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas-2.jpg\" class=\"attachment-full size-full wp-image-13935\" alt=\"Lidji | Attorney | The LIDJI Law Firm | Personal Injury Attorney | Dallas Houston Texas 2\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas-2.jpg 1440w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas-2-150x45.jpg 150w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f71c20a dpn_des elementor-widget elementor-widget-image\" data-id=\"f71c20a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"439\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas.jpg\" class=\"attachment-full size-full wp-image-13931\" alt=\"Lidji | Attorney | The LIDJI Law Firm | Personal Injury Attorney | Dallas Houston Texas\" srcset=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas.jpg 528w, https:\/\/thelidjifirm.com\/wp-content\/uploads\/Lidji-Attorney-The-LIDJI-Law-Firm-Personal-Injury-Attorney-Dallas-Houston-Texas-150x125.jpg 150w\" sizes=\"(max-width: 528px) 100vw, 528px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac85b2 elementor-widget__width-auto elementor-absolute dpn_des dpn_tab elementor-widget elementor-widget-image\" data-id=\"0ac85b2\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/the_lidji_firm-500_million_recovered.svg\" title=\"\" alt=\"500 Million Recovered | The Lidji Firm\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-99da631 elementor-section-full_width elementor-reverse-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"99da631\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbebab2 fce-text \" data-id=\"fbebab2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfed215 elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"cfed215\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h2 class=\"raven-heading raven-heading-h2\"><span class=\"raven-heading-title \">\u00bfCu\u00e1nto vale tu caso?<\/span><\/h2><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e38c63a elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"e38c63a\" data-element_type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h3 class=\"raven-heading raven-heading-h3\"><span class=\"raven-heading-title \">Env\u00ede para una evaluaci\u00f3n de caso gratuita<\/span><\/h3><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23884c1 elementor-widget elementor-widget-text-editor\" data-id=\"23884c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Representamos a clientes de todo Texas y de todo el pa\u00eds. Si has sufrido alg\u00fan accidente por la negligencia de otra persona o empresa, o a causa de un producto defectuoso, un medicamento en mal estado o un profesional sanitario, el Bufete Lidji te ofrece una revisi\u00f3n gratuita y confidencial de tu caso para ayudarte a comprender tus opciones y posibles v\u00edas de actuaci\u00f3n.<\/p>\n<p>La consulta no cuesta nada y la conversaci\u00f3n es confidencial. La indemnizaci\u00f3n puede consistir en gastos m\u00e9dicos, p\u00e9rdida de ingresos, dolor y sufrimiento, da\u00f1os materiales y otros.<\/p>\n<p>Nuestro bufete est\u00e1 a tu disposici\u00f3n para responder a tus preguntas y atender tus preocupaciones, y estamos preparados para proporcionar a tu caso el asesoramiento atento y la firme defensa necesarios para luchar por la justicia en tu nombre.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1a0283b h0 fce-text \" data-id=\"1a0283b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12917b1 elementor-align-right elementor-mobile-align-center call_box elementor-widget__width-auto elementor-widget elementor-widget-raven-button\" data-id=\"12917b1\" data-element_type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"tel:(800)%20223-7455\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\t<span class=\"ln1\">Consulta gratuita 24\/7 con un abogado<\/span><span class=\"ln2\"><i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i> (800) 223-7455<\/span>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e60fdf2 elementor-widget__width-auto elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"e60fdf2\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thelidjifirm.com\/wp-content\/uploads\/the_lidji_firm-500_million_recovered.svg\" title=\"\" alt=\"500 Million Recovered | The Lidji Firm\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e934f3e elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e934f3e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-3a61aaf\" data-id=\"3a61aaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-f0380c4\" data-id=\"f0380c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f981f6 elementor-widget elementor-widget-shortcode\" data-id=\"7f981f6\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-5309\"><form id=\"wpforms-form-5309\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"5309\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/10028\" data-token=\"1f818f618498ee0dcfbad77936ee8796\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-5309-field_0-container\" class=\"wpforms-field wpforms-field-name wpf_fce fce_name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5309-field_0\">Nombre completo <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-5309-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Nombre completo\" required><\/div><div id=\"wpforms-5309-field_5-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half wpforms-first wpf_fce fce_phone\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5309-field_5\">Tel\u00e9fono <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-5309-field_5\" class=\"wpforms-field-large wpforms-field-required wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][5]\" placeholder=\"Tel\u00e9fono\" required><\/div><div id=\"wpforms-5309-field_1-container\" class=\"wpforms-field wpforms-field-email wpf_fce fce_email wpforms-one-half\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5309-field_1\">Correo Electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-5309-field_1\" class=\"wpforms-field-large wpforms-field-required\" data-rule-restricted-email=\"1\" name=\"wpforms[fields][1]\" placeholder=\"Correo Electr\u00f3nico\" spellcheck=\"false\" required><\/div><div id=\"wpforms-5309-field_4-container\" class=\"wpforms-field wpforms-field-select wpf_fce fce_casetype wpforms-field-select-style-modern\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5309-field_4\">Tipo de caso<\/label><select id=\"wpforms-5309-field_4\" class=\"wpforms-field-medium choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-medium\" data-search-enabled=\"1\" name=\"wpforms[fields][4][]\" multiple=\"multiple\"><option value=\"\" class=\"placeholder\" disabled >Tipo de caso (opcional)<\/option><option value=\"Agravio masivo - BadPill\" >Agravio masivo - BadPill<\/option><option value=\"Demanda de Camp Lejeune\" >Demanda de Camp Lejeune<\/option><option value=\"Defecto de nacimiento infantil \u2013 Lesi\u00f3n de nacimiento\" >Defecto de nacimiento infantil \u2013 Lesi\u00f3n de nacimiento<\/option><option value=\"Demanda de Johnson &amp; Johnson Powder\" >Demanda de Johnson &amp; Johnson Powder<\/option><option value=\"Demanda de Roundup\" >Demanda de Roundup<\/option><option value=\"Demanda de CPAP de Phillips\" >Demanda de CPAP de Phillips<\/option><option value=\"Demanda de Paraquat\" >Demanda de Paraquat<\/option><option value=\"C\u00e1ncer de Zantac\" >C\u00e1ncer de Zantac<\/option><option value=\"Demandas de Januvia\" >Demandas de Januvia<\/option><option value=\"Demanda por problemas card\u00edacos de Zofran\" >Demanda por problemas card\u00edacos de Zofran<\/option><option value=\"Mala praxis m\u00e9dica\" >Mala praxis m\u00e9dica<\/option><option value=\"Demanda de filtro IVC\" >Demanda de filtro IVC<\/option><option value=\"Lesiones personales\" >Lesiones personales<\/option><option value=\"Accidente de cami\u00f3n\" >Accidente de cami\u00f3n<\/option><option value=\"Accidente de auto\" >Accidente de auto<\/option><option value=\"Accidente de motocicleta\" >Accidente de motocicleta<\/option><option value=\"Accidentes por conducir ebrio\" >Accidentes por conducir ebrio<\/option><option value=\"Responsabilidad de la tienda de dram\" >Responsabilidad de la tienda de dram<\/option><option value=\"Accidentes de construcci\u00f3n\" >Accidentes de construcci\u00f3n<\/option><option value=\"Responsabilidad de los locales\" >Responsabilidad de los locales<\/option><option value=\"Responsabilidad del producto\" >Responsabilidad del producto<\/option><option value=\"Muerte injusta\" >Muerte injusta<\/option><\/select><\/div><div id=\"wpforms-5309-field_2-container\" class=\"wpforms-field wpforms-field-textarea wpf_fce fce_casedetail\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5309-field_2\">Detalle del caso <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-5309-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Por favor describe tu caso\" required><\/textarea><\/div><div id=\"wpforms-5309-field_8-container\" class=\"wpforms-field wpforms-field-date-time wpf_fce wpforms-one-half wpforms-first\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-5309-field_8\">Fecha del accidente <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-5309-field_8\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"F j, Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][8][date]\" placeholder=\"Por favor seleccione\" required><a title=\"Borrar fecha\" data-clear class=\"wpforms-datepicker-clear\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-5309-field_9-container\" class=\"wpforms-field wpforms-field-radio wpforms-one-half wpf_fce wpforms-list-2-columns\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-5309-field_9\">\u00bfYa tienes abogado? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-5309-field_9\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-5309-field_9_1\" name=\"wpforms[fields][9]\" value=\"S\u00ed\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5309-field_9_1\">S\u00ed<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-5309-field_9_2\" name=\"wpforms[fields][9]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-5309-field_9_2\">No<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"5309\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"8\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5309\" class=\"wpforms-submit\" data-alt-text=\"Enviar...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/thelidjifirm.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\" title=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-46f38f9\" data-id=\"46f38f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En todo el pa\u00eds Demandas contra Phillips CPAP Abogados de lesiones personales REVISI\u00d3N GRATUITA DEL CASO Cuando tienes una enfermedad que afecta gravemente a tu vida y a tu salud, probablemente est\u00e9s centrado en lo que puedes hacer para mejorar. Muchas personas que padecen apnea del sue\u00f1o utilizaron un aparato de Philips Respironics, y en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":41,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10028","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/pages\/10028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/comments?post=10028"}],"version-history":[{"count":15,"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/pages\/10028\/revisions"}],"predecessor-version":[{"id":14151,"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/pages\/10028\/revisions\/14151"}],"wp:attachment":[{"href":"https:\/\/thelidjifirm.com\/es\/wp-json\/wp\/v2\/media?parent=10028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}